{"id":9929,"date":"2024-10-17T10:36:13","date_gmt":"2024-10-17T15:36:13","guid":{"rendered":"https:\/\/colombiaopina.com.co\/?p=9929"},"modified":"2024-10-17T11:03:37","modified_gmt":"2024-10-17T16:03:37","slug":"indigenas-ahora-tendran-el-control-ambiental-de-sus-territorios-el-gobierno-otorga-las-mismas-facultades-que-las-car","status":"publish","type":"post","link":"https:\/\/colombiaopina.com.co\/index.php\/2024\/10\/17\/indigenas-ahora-tendran-el-control-ambiental-de-sus-territorios-el-gobierno-otorga-las-mismas-facultades-que-las-car\/","title":{"rendered":"Nuevo proyecto de Ley busca articular la justicia ind\u00edgena con la justicia ordinaria: \u00bfafectar\u00e1 el debido proceso?"},"content":{"rendered":"<p>Un importante proyecto de Ley que pretende coordinar la justicia ind\u00edgena con la justicia ordinaria ha sido presentado al Congreso de la Rep\u00fablica. La iniciativa, que es producto de un trabajo conjunto entre el Ministerio de Justicia, el Consejo Superior de la Judicatura y autoridades ind\u00edgenas, tiene como objetivo establecer mecanismos claros para articular ambos sistemas judiciales, respetando la autonom\u00eda de las comunidades ind\u00edgenas, reconocida en el art\u00edculo 246 de la Constituci\u00f3n.<\/p><p>El proyecto de Ley 287 ofrece un marco legal para que las comunidades ind\u00edgenas ejerzan su propia jurisdicci\u00f3n sin generar conflictos con la justicia ordinaria, una situaci\u00f3n que ha suscitado preocupaciones en el pasado por posibles casos de impunidad. Seg\u00fan los proponentes, la iniciativa busca, entre otras cosas, fortalecer el acceso a la justicia, respetar los derechos fundamentales y mejorar la seguridad jur\u00eddica. Adem\u00e1s, se reconoce la riqueza cultural y jur\u00eddica de los pueblos ind\u00edgenas, cuyo sistema de justicia responde a sus propias cosmovisiones y valores.<\/p><figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"652\" height=\"366\" src=\"https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/2-Las-claves-del-proyecto-de-ley-que-busca-coordinar-la-jurisdiccion-especial-indigena-con-la-justicia-ordinaria-\u00bfse-prestara-para-la-impunidad.jpeg\" alt=\"\" class=\"wp-image-9931\" srcset=\"https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/2-Las-claves-del-proyecto-de-ley-que-busca-coordinar-la-jurisdiccion-especial-indigena-con-la-justicia-ordinaria-\u00bfse-prestara-para-la-impunidad.jpeg 652w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/2-Las-claves-del-proyecto-de-ley-que-busca-coordinar-la-jurisdiccion-especial-indigena-con-la-justicia-ordinaria-\u00bfse-prestara-para-la-impunidad-300x168.jpeg 300w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/2-Las-claves-del-proyecto-de-ley-que-busca-coordinar-la-jurisdiccion-especial-indigena-con-la-justicia-ordinaria-\u00bfse-prestara-para-la-impunidad-150x84.jpeg 150w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/2-Las-claves-del-proyecto-de-ley-que-busca-coordinar-la-jurisdiccion-especial-indigena-con-la-justicia-ordinaria-\u00bfse-prestara-para-la-impunidad-600x337.jpeg 600w\" sizes=\"(max-width: 652px) 100vw, 652px\" \/><\/figure><p>Uno de los aspectos m\u00e1s llamativos del proyecto es la inclusi\u00f3n de mediadores ling\u00fc\u00edsticos para garantizar que las personas involucradas en un proceso, ya sean acusados o v\u00edctimas, comprendan adecuadamente los recursos y procedimientos legales. Tambi\u00e9n se contempla la creaci\u00f3n de mecanismos de cooperaci\u00f3n entre las autoridades ind\u00edgenas y las instancias de la justicia ordinaria para asegurar la aprehensi\u00f3n de procesados y el intercambio de informaci\u00f3n, con el fin de evitar la impunidad en delitos graves.<\/p><p>A pesar de las ventajas que plantea esta coordinaci\u00f3n interjurisdiccional, el proyecto ha generado inquietudes sobre el impacto que podr\u00eda tener en el debido proceso. Los cr\u00edticos se\u00f1alan que algunas pr\u00e1cticas de la justicia ind\u00edgena, como el fuete o el cepo, podr\u00edan no ser proporcionales en casos de delitos graves, como la violencia sexual. Sin embargo, desde el Ministerio de Justicia han asegurado que el proyecto no elimina ni limita la jurisdicci\u00f3n de los jueces ordinarios y que los castigos de la jurisdicci\u00f3n ind\u00edgena no podr\u00e1n violar derechos fundamentales, tales como el derecho a la vida o la prohibici\u00f3n de tratos crueles&nbsp;e&nbsp;inhumanos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un importante proyecto de Ley que pretende coordinar la justicia ind\u00edgena con la justicia ordinaria ha sido presentado al Congreso de la Rep\u00fablica. La iniciativa, que es producto de un trabajo conjunto entre el Ministerio de Justicia, el Consejo Superior de la Judicatura y autoridades ind\u00edgenas, tiene como objetivo establecer mecanismos claros para articular ambos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[39,46,2752],"tags":[93,227,167,426,135,2755],"class_list":{"0":"post-9929","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-colombia","8":"category-gobierno","9":"category-indigenas","10":"tag-colombia","11":"tag-gobierno","12":"tag-indigenas","13":"tag-medio-ambiente","14":"tag-petro","15":"tag-territorios"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/Las-claves-del-proyecto-de-ley-que-busca-coordinar-la-jurisdiccion-especial-indigena-con-la-justicia-ordinaria-\u00bfse-prestara-para-la-impunidad.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/9929"}],"collection":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=9929"}],"version-history":[{"count":2,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/9929\/revisions"}],"predecessor-version":[{"id":9956,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/9929\/revisions\/9956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/media\/9930"}],"wp:attachment":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=9929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=9929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=9929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}