{"id":9732,"date":"2024-10-10T10:48:22","date_gmt":"2024-10-10T15:48:22","guid":{"rendered":"https:\/\/colombiaopina.com.co\/?p=9732"},"modified":"2024-10-10T10:48:23","modified_gmt":"2024-10-10T15:48:23","slug":"banco-mundial-mejora-proyeccion-de-crecimiento-para-colombia-en-2024-estimacion-sube-a-15","status":"publish","type":"post","link":"https:\/\/colombiaopina.com.co\/index.php\/2024\/10\/10\/banco-mundial-mejora-proyeccion-de-crecimiento-para-colombia-en-2024-estimacion-sube-a-15\/","title":{"rendered":"Banco Mundial mejora proyecci\u00f3n de crecimiento para Colombia en 2024: estimaci\u00f3n sube a 1,5%"},"content":{"rendered":"<p>El Banco Mundial ha ajustado al alza su proyecci\u00f3n de crecimiento econ\u00f3mico para Colombia en 2024, pasando del 1,3% previamente estimado al 1,5%, seg\u00fan el informe Impuestos a la riqueza para la equidad y el crecimiento publicado este 9 de octubre. Este repunte est\u00e1 impulsado por varios factores clave, entre los que se destacan la desaceleraci\u00f3n de la inflaci\u00f3n y los recortes en las tasas de inter\u00e9s por parte del Banco de la Rep\u00fablica, lo que podr\u00eda ayudar a impulsar la inversi\u00f3n.<\/p><p>La regi\u00f3n de Am\u00e9rica Latina y el Caribe, de la cual Colombia forma parte, proyecta un crecimiento del 1,9% en 2024, con una aceleraci\u00f3n hasta el 2,6% en 2025. Sin embargo, el informe tambi\u00e9n subraya que estas cifras representan las tasas de crecimiento m\u00e1s bajas a nivel mundial, evidenciando los obst\u00e1culos estructurales que enfrenta la regi\u00f3n, como la alta dependencia del consumo y la limitada inversi\u00f3n debido a las tasas de inter\u00e9s elevadas.<\/p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5-1024x682.jpeg\" alt=\"\" class=\"wp-image-9733\" srcset=\"https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5-1024x682.jpeg 1024w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5-300x200.jpeg 300w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5-768x512.jpeg 768w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5-150x100.jpeg 150w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5-696x464.jpeg 696w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5-1068x712.jpeg 1068w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5-600x400.jpeg 600w, https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9.1-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><p>Colombia, que ha enfrentado un panorama econ\u00f3mico complicado, se beneficiar\u00eda de tendencias globales como la transici\u00f3n energ\u00e9tica y el nearshoring, seg\u00fan declar\u00f3 William Maloney, economista jefe del Banco Mundial para Am\u00e9rica Latina. Maloney destac\u00f3 el potencial de ciudades como Barranquilla y Cali, con su mano de obra calificada y una infraestructura en crecimiento, como polos atractivos para las multinacionales. No obstante, se\u00f1al\u00f3 la importancia de asegurar un marco de estabilidad jur\u00eddica y fiscal para atraer inversiones tanto locales como extranjeras.<\/p><p>Aunque las perspectivas de crecimiento son alentadoras, el informe advierte que la regi\u00f3n debe continuar aprovechando las condiciones favorables para atraer inversiones sostenibles y consolidar un crecimiento econ\u00f3mico a largo plazo, superando los retos que ha dejado la pandemia y la inestabilidad&nbsp;global.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Banco Mundial ha ajustado al alza su proyecci\u00f3n de crecimiento econ\u00f3mico para Colombia en 2024, pasando del 1,3% previamente estimado al 1,5%, seg\u00fan el informe Impuestos a la riqueza para la equidad y el crecimiento publicado este 9 de octubre. Este repunte est\u00e1 impulsado por varios factores clave, entre los que se destacan la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2673,39,89],"tags":[2674,93,2675,541],"class_list":{"0":"post-9732","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-banco-mundial","8":"category-colombia","9":"category-economia","10":"tag-banco-mundial","11":"tag-colombia","12":"tag-crecimiento-economico","13":"tag-economia"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/10\/9-Banco-Mundial-eleva-la-proyeccion-de-crecimiento-de-Colombia-para-2024-a-1.5.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/9732"}],"collection":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=9732"}],"version-history":[{"count":1,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/9732\/revisions"}],"predecessor-version":[{"id":9735,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/9732\/revisions\/9735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/media\/9734"}],"wp:attachment":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=9732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=9732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=9732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}