{"id":584,"date":"2024-01-23T09:28:48","date_gmt":"2024-01-23T14:28:48","guid":{"rendered":"https:\/\/colombiaopina.com.co\/?p=584"},"modified":"2024-01-23T09:28:51","modified_gmt":"2024-01-23T14:28:51","slug":"reforma-radical-gobernador-de-antioquia-lucha-por-la-autonomia-fiscal-de-las-regiones","status":"publish","type":"post","link":"https:\/\/colombiaopina.com.co\/index.php\/2024\/01\/23\/reforma-radical-gobernador-de-antioquia-lucha-por-la-autonomia-fiscal-de-las-regiones\/","title":{"rendered":"Reforma Radical: Gobernador de Antioquia Lucha por la Autonom\u00eda Fiscal de las Regiones"},"content":{"rendered":"<p>En una reciente reuni\u00f3n con el senador Humberto de la Calle, el gobernador de Antioquia, Andr\u00e9s Juli\u00e1n, defendi\u00f3 su propuesta de referendo constitucional que busca otorgar mayor autonom\u00eda fiscal a las regiones colombianas. El gobernador enfatiz\u00f3 que su iniciativa no busca federalizar el pa\u00eds ni independizar a Antioquia, sino asegurar justicia y equidad para todas las regiones.<br><br><\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">El Senador <a href=\"https:\/\/twitter.com\/DeLaCalleHum?ref_src=twsrc%5Etfw\">@DeLaCalleHum<\/a> le dice s\u00ed al debate sobre Autonom\u00eda Fiscal para las Regiones que propone Antioquia, un asunto de inter\u00e9s nacional en el que seguiremos sumando voces. <a href=\"https:\/\/t.co\/tqQPOzh445\">pic.twitter.com\/tqQPOzh445<\/a><\/p>&mdash; Andr\u00e9s Juli\u00e1n (@AndresJRendonC) <a href=\"https:\/\/twitter.com\/AndresJRendonC\/status\/1749549185093820928?ref_src=twsrc%5Etfw\">January 22, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Hoy nos tomamos el tinto con <a href=\"https:\/\/twitter.com\/AndresJRendonC?ref_src=twsrc%5Etfw\">@AndresJRendonC<\/a> para hablar sobre un tema crucial: La Autonom\u00eda Regional. Muy productiva conversaci\u00f3n que formula varias reflexiones. Regionalizar el pa\u00eds con criterios m\u00e1s modernos es una deuda en Colombia desde hace d\u00e9cadas. La autonom\u00eda fiscal y\u2026 <a href=\"https:\/\/t.co\/9DnLmFkvHX\">pic.twitter.com\/9DnLmFkvHX<\/a><\/p>&mdash; Humberto de la Calle (@DeLaCalleHum) <a href=\"https:\/\/twitter.com\/DeLaCalleHum\/status\/1749588344042828228?ref_src=twsrc%5Etfw\">January 23, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p>La propuesta del gobernador Andr\u00e9s Juli\u00e1n se centra en modificar el art\u00edculo 298 de la Constituci\u00f3n Nacional para permitir que los impuestos de renta y patrimonio sean administrados por los departamentos, aumentando as\u00ed sus ingresos. Esta medida garantizar\u00eda que ning\u00fan departamento reciba menos recursos o vea afectadas sus finanzas.<\/p><p>El senador Humberto de la Calle, conocido por ser uno de los padres de la Constituci\u00f3n de 1991, reconoci\u00f3 que el papel de los departamentos qued\u00f3 poco claro en la Carta Magna. Coincidi\u00f3 con el gobernador en la necesidad de corregir esta situaci\u00f3n y apoy\u00f3 la idea de una mayor autonom\u00eda para las regiones.<br><br><\/p><p>El gobernador Andr\u00e9s Juli\u00e1n reafirm\u00f3 su compromiso con el desarrollo regional, argumentando que los recursos generados en las regiones deben ser utilizados para resolver problemas locales. Critic\u00f3 el derroche del gobierno central y subray\u00f3 la importancia de que las regiones no paguen por excesos burocr\u00e1ticos ajenos a sus necesidades.<\/p>","protected":false},"excerpt":{"rendered":"<p>En una reciente reuni\u00f3n con el senador Humberto de la Calle, el gobernador de Antioquia, Andr\u00e9s Juli\u00e1n, defendi\u00f3 su propuesta de referendo constitucional que busca otorgar mayor autonom\u00eda fiscal a las regiones colombianas. El gobernador enfatiz\u00f3 que su iniciativa no busca federalizar el pa\u00eds ni independizar a Antioquia, sino asegurar justicia y equidad para todas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[38,46],"tags":[],"class_list":{"0":"post-584","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-antioquia","8":"category-gobierno"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/01\/GEfJQEDWoAAWQW9.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/584"}],"collection":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=584"}],"version-history":[{"count":1,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/584\/revisions"}],"predecessor-version":[{"id":586,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/584\/revisions\/586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/media\/585"}],"wp:attachment":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}