{"id":287,"date":"2024-01-15T17:42:50","date_gmt":"2024-01-15T16:42:50","guid":{"rendered":"https:\/\/colombiaopina.com.co\/?p=287"},"modified":"2024-01-15T23:02:45","modified_gmt":"2024-01-15T22:02:45","slug":"el-presidente-petro-cancelo-su-viaje-a-davos-tras-quedarse-en-guatemala-para-la-posesion-de-bernardo-arevalo-regresara-a-colombia","status":"publish","type":"post","link":"https:\/\/colombiaopina.com.co\/index.php\/2024\/01\/15\/el-presidente-petro-cancelo-su-viaje-a-davos-tras-quedarse-en-guatemala-para-la-posesion-de-bernardo-arevalo-regresara-a-colombia\/","title":{"rendered":"El presidente Petro cancel\u00f3 su viaje a Davos tras quedarse en Guatemala para la posesi\u00f3n de Bernardo Ar\u00e9valo: regresar\u00e1 a Colombia"},"content":{"rendered":"<p>El presidente Gustavo Petro cancel\u00f3 su viaje a Davos que estaba previsto para esta semana tras quedarse un d\u00eda m\u00e1s en Guatemala en la posesi\u00f3n del nuevo mandatario de ese pa\u00eds, Bernardo Ar\u00e9valo, quien tom\u00f3 juramento del cargo durante la media noche del domingo tras una crisis pol\u00edtica interna en su pa\u00eds.<\/p><p>El jefe de Estado colombiano ten\u00eda programada agenda en la sede del Foro Econ\u00f3mico Mundial, pero su itinerario en Suiza comenz\u00f3 a tambalear desde la tarde del domingo cuando \u00e9l afirm\u00f3 en su cuenta de X (antes Twitter) que se quedar\u00eda en la naci\u00f3n centroamericana hasta que se concretara la posesi\u00f3n.<\/p><p>La agenda pol\u00edtica en Guatemala se alarg\u00f3 en medio de las tensiones internas en el Congreso en el que una parte de las bancadas quer\u00eda desconocer al partido de Ar\u00e9valo que acababa de ser suspendido por la Fiscal\u00eda y, por tanto, enredar su elecci\u00f3n. Al final, el presidente guatemalteco termin\u00f3 juramentando su cargo.<\/p><p>La posesi\u00f3n de Ar\u00e9valo se tard\u00f3 varias horas porque el Legislativo no se pon\u00eda de acuerdo para elegir la mesa directiva para el nuevo periodo en el Congreso. Mientras los parlamentarios intentaban dirimir sus disputas internas, varios mandatarios y cancilleres latinoamericanos presionaban para que se concretara la jornada democr\u00e1tica.<\/p><p>\u201cInforme desde Guatemala. La Fiscal\u00eda ha sido orquestadora de un golpe de estado. El Congreso ha dificultado la posesi\u00f3n del presidente electo. La Corte Constitucional se apresta a defender la democracia y el voto popular\u201d, escribi\u00f3 el presidente Petro en X.<\/p><p>La posesi\u00f3n de Bernardo Ar\u00e9valo iba a llevarse a cabo al medio d\u00eda del domingo (14 de enero). Cuando ya eran las 8 de la noche de ese d\u00eda, el mandatario guatemalteco no hab\u00eda logrado tomar posesi\u00f3n y el mandatario colombiano anunci\u00f3 que la delegaci\u00f3n colombiana no se retirar\u00eda del pa\u00eds hasta que se diera su investidura oficial.<\/p><p>\u201cEstar\u00e9 en Ciudad Guatemala, no se retira la delegaci\u00f3n colombiana hasta la posesi\u00f3n del presidente Ar\u00e9valo. Vamos al Teatro Nacional Miguel \u00c1ngel Asturias donde debe posesionarse el presidente Bernardo Ar\u00e9valo. Si es necesario se suspende el viaje a Davos\u201d, enfatiz\u00f3 el jefe de Estado en la noche del domingo.<\/p><p>Y as\u00ed fue. La investidura de Bernardo Ar\u00e9valo solo se concret\u00f3 cuando se acercaba la media noche del domingo y el itinerario que deb\u00eda cumplir el presidente Petro para llegar a Davos termin\u00f3 siendo cancelado.<\/p><p>La visita oficial de Gustavo Petro a Suiza estaba programada para este mi\u00e9rcoles 17 de enero y su objetivo era defender su pol\u00edtica de lucha contra el cambio clim\u00e1tico y llamar la atenci\u00f3n sobre la necesidad de acelerar la translaci\u00f3n energ\u00e9tica por encima de la producci\u00f3n de hidrocarburos.<\/p><p><strong>Petro en la posesi\u00f3n de Ar\u00e9valo <\/strong><\/p><p>El presidente Gustavo Petro fue saludado entre aplausos y con una ovaci\u00f3n en pie por parte de los asistentes a la posesi\u00f3n de Bernardo Ar\u00e9valo que tuvo lugar en Ciudad de Guatemala. Una vez se concret\u00f3 la investidura presidencial, el jefe de Estado colombiano subi\u00f3 al escenario y salud\u00f3 al p\u00fablico junto a Ar\u00e9valo y la vicepresidenta Karin Herrera.<\/p><p>El mandatario Ar\u00e9valo logr\u00f3 posesionarse despu\u00e9s de una jornada en la que varios integrantes del Gobierno de Colombia cerraron filas entorno a la crisis pol\u00edtica de Guatemala.<\/p><p>La ministra de Ambiente, Susana Muhamad, sostuvo que \u201cel presidente Gustavo Petro mostr\u00f3 solidaridad con el pueblo de Guatemala y una firme convicci\u00f3n de defender la democracia en nuestro continente. En su discurso el Presidente Ar\u00e9valo advirti\u00f3 los riesgos reales de que el pa\u00eds hubiese ca\u00eddo en el autoritarismo\u201d.<\/p><p>Otro que result\u00f3 determinante durante esta disputa pol\u00edtica fue el ministro de Defensa, Iv\u00e1n Vel\u00e1squez, quien hab\u00eda sido comisionado de Naciones Unidad contra la impunidad en ese pa\u00eds e, incluso, tuvo problemas para ingresar a territorio guatemalteco.<\/p><p>El ministro Vel\u00e1squez escribi\u00f3 que \u201clos ojos del mundo est\u00e1n puestos sobre Guatemala y no debe apartarlos despu\u00e9s de la posesi\u00f3n de Bernardo Ar\u00e9valo. La comunidad internacional debe permanecer atenta y acompa\u00f1ar al nuevo gobierno, para asegurar que los intentos golpistas sean definitivamente erradicados\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente Gustavo Petro cancel\u00f3 su viaje a Davos que estaba previsto para esta semana tras quedarse un d\u00eda m\u00e1s en Guatemala en la posesi\u00f3n del nuevo mandatario de ese pa\u00eds, Bernardo Ar\u00e9valo, quien tom\u00f3 juramento del cargo durante la media noche del domingo tras una crisis pol\u00edtica interna en su pa\u00eds. El jefe de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[46,53],"tags":[],"class_list":{"0":"post-287","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gobierno","8":"category-internacional"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/colombiaopina.com.co\/wp-content\/uploads\/2024\/01\/Petro.png","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/287"}],"collection":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/comments?post=287"}],"version-history":[{"count":1,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/287\/revisions"}],"predecessor-version":[{"id":289,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/posts\/287\/revisions\/289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/media\/288"}],"wp:attachment":[{"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/media?parent=287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/categories?post=287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colombiaopina.com.co\/index.php\/wp-json\/wp\/v2\/tags?post=287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}